{"id":1333,"date":"2020-09-26T15:03:02","date_gmt":"2020-09-26T13:03:02","guid":{"rendered":"https:\/\/conservativeenthusiast.com\/?p=1333"},"modified":"2020-11-11T15:43:56","modified_gmt":"2020-11-11T14:43:56","slug":"qui-est-vraiment-arthur-schopenhauer","status":"publish","type":"post","link":"https:\/\/conservativenthusiast.com\/en\/qui-est-vraiment-arthur-schopenhauer\/","title":{"rendered":"Qui est vraiment Arthur Schopenhauer ?"},"content":{"rendered":"<h2 class=\"wp-block-heading\"><strong><span class=\"has-inline-color has-black-color\">Introduction<\/span><\/strong><\/h2>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-justify\">Arthur Schopenhauer est un philosophe allemand atypique connu pour son immense influence sur de nombreux philosophes, \u00e9crivains et artistes du XIX et XXe si\u00e8cle. Son plus grand disciple, le g\u00e9nial et l\u2019intemporel <a href=\"https:\/\/conservativenthusiast.com\/en\/nietzsche-plus-actuel-que-jamais\/\" target=\"_blank\" rel=\"noreferrer noopener\">Friedrich Nietzsche<\/a>, \u00e0 qui il insuffle les grandes lignes de sa philosophie, c\u00e9l\u00e8bre volontiers le g\u00e9nie de son \u00e9ducateur, malgr\u00e9 sa d\u00e9sapprobation par la suite. Derri\u00e8re un personnage trop souvent pr\u00e9sent\u00e9 -\u00e0 tort- comme antipathique, myosine, misanthrope, acari\u00e2tre, grincheux, m\u00e9prisant, arrogant, solitaire, et que sais-je encore&nbsp;; se cache en r\u00e9alit\u00e9 une toute autre facette nous r\u00e9v\u00e9lant une philosophie tout aussi complexe et fascinante que profond\u00e9ment philanthropique. \u00c0 travers cette dualit\u00e9 qui semble habiter \u00e0 la fois l\u2019homme et le philosophe, l\u2019illusion paradoxale que sa pens\u00e9e pourrait laisser entrevoir au premier abord, se dessine finalement un portrait complet et nuanc\u00e9 d\u2019un individu qui aura marqu\u00e9 son \u00e9poque. Banal loufoque ou grand sage, saum\u00e2tre forcen\u00e9 ou g\u00e9nie d\u00e9\u00e7u, qui est v\u00e9ritablement l\u2019intrigant Arthur Schopenhauer&nbsp;?<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><span class=\"has-inline-color has-black-color\">Une enfance r\u00e9v\u00e9latrice<\/span><\/strong><\/h2>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-justify\">N\u00e9 le 22 f\u00e9vrier 1788 \u00e0 Danzig, Arthur Schopenhauer est le fruit du mariage entre Johanna Henriette Trosiener, grande femme de lettre&nbsp;; et Henri Floris Schopenhauer, c\u00e9l\u00e8bre commer\u00e7ant lib\u00e9ral. Fils de bonne famille, il est pourtant r\u00e9guli\u00e8rement en conflit avec ses parents -et particuli\u00e8rement avec sa m\u00e8re- et ne cessera de nouer avec eux des relations pour le moins conflictuelles. D\u00e8s l\u2019enfance, Arthur veut faire de la philosophie et des \u00e9tudes, ce qui n\u2019est pas de l\u2019avis de son p\u00e8re qui souhaite qu\u2019il devienne comme lui un grand commer\u00e7ant, persuad\u00e9 que le m\u00e9tier de professeur ne pourra lui permettre de vivre d\u00e9cemment et qu\u2019il ne pourra comprendre le monde qu\u2019en voyageant. Ainsi, contre la volont\u00e9 du jeune Arthur, ses parents d\u00e9cident de l\u2019emmener pendant pr\u00e8s de deux ans d\u00e9couvrir l\u2019Europe dans un voyage formateur. C\u2019est au cours de ce voyage, lorsqu\u2019il rencontre les bagnards de Toulon, que le jeune Arthur alors \u00e2g\u00e9 de 15 ou de 16 ans \u00e9prouve une \u00e9motion absolument bouleversante et qui, sans nul doute, le marquera de fa\u00e7on ind\u00e9l\u00e9bile. Il est absolument horrifi\u00e9 par ce qu\u2019il y voit&nbsp;:<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><em>&nbsp;\u00ab&nbsp;Je consid\u00e8re que le sort de ces malheureux est beaucoup plus affreux que celui des condamn\u00e9s \u00e0 mort. Les gal\u00e8res que j\u2019ai vues de l\u2019ext\u00e9rieur semblent \u00eatre les endroits les plus sales et les plus \u00e9c\u0153urants que l\u2019on puisse imaginer.&nbsp;\u00bb<\/em><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-justify\"><em>\u00ab Peut-on imaginer un sentiment plus affreux que celui qu\u2019\u00e9prouve un malheureux qui est encha\u00een\u00e9 au banc d\u2019une gal\u00e8re sombre, d\u2019o\u00f9 seule la mort peut le d\u00e9tacher ? \u00bb<\/em><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-justify\">Cette attitude de l\u2019adolescent, afflig\u00e9 par cette vision terrible, est n\u00e9anmoins r\u00e9v\u00e9latrice du caract\u00e8re profond du futur philosophe. Cette sensibilit\u00e9 immense, cette profonde empathie cognitive et \u00e9motionnelle \u00e0 l\u2019\u00e9gard des hommes laisse entrevoir en lui, d\u00e8s son jeune \u00e2ge, un humanisme sinc\u00e8re et une v\u00e9ritable tendresse bless\u00e9e&nbsp;:<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-justify\"><em>\u00ab Et quand arrive enfin le moment qu\u2019il d\u00e9sire depuis dix ou douze ans, ou ce qui est plus rare, depuis vingt ans, avec des soupirs quotidiens de d\u00e9sespoir, c\u2019est-\u00e0-dire la fin de l\u2019esclavage, que devient-il ? Peut-il revenir dans un monde pour lequel il est mort depuis dix ans ? Les chances qu\u2019il avait dix ans auparavant lorsqu\u2019il \u00e9tait plus jeune ont disparu. Personne ne veut prendre celui qui revient d\u2019une gal\u00e8re, et dix ans de ch\u00e2timent ne l\u2019ont pas lav\u00e9 du crime d\u2019un moment. \u00bb<\/em><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><span class=\"has-inline-color has-black-color\">L\u2019humanisme d\u00e9\u00e7u<\/span><\/strong><\/h2>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-justify\">De cette souffrance \u00e9prouv\u00e9e \u00e0 travers ces hommes enchain\u00e9s, assoiff\u00e9s, affam\u00e9s, terrass\u00e9s ; Schopenhauer en dresse une conclusion gla\u00e7ante&nbsp;: c\u2019est cette souffrance qui est la condition humaine. Chaque fois qu\u2019il \u00e9voque la souffrance du monde, cette d\u00e9tresse lamentable encr\u00e9e en chacun de nous, Schopenhauer, d\u2019une \u00e9loquence remarquable, l\u2019\u00e9voque avec une v\u00e9h\u00e9mence tranchante. Par son exp\u00e9rience et sa v\u00e9rit\u00e9, il dresse le constat de la mis\u00e8re du monde et la cloue au pilori. Il tire cependant une \u00e9trange satisfaction en constatant cette r\u00e9volte en nous, cette protestation de l\u2019esprit face \u00e0 cette condition de souffrance. De railleries sarcastiques qu\u2019il lance \u00e0 la vie, d\u2019envol\u00e9es superbes coupl\u00e9es \u00e0 des citations grecques et latines, de cette exaltation de la r\u00e9volte en nous, Schopenhauer pourfend de son verbe vengeur et grandiose la mis\u00e8re et la souffrance en chacun de nous. Cette mis\u00e8re humaine, cette insupportable souffrance, c\u2019est la sienne, c\u2019est la n\u00f4tre, c\u2019est la tienne.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">N\u2019est-il pas plus empathique que celui qui \u00e9prouve la souffrance de chacun et de tous&nbsp;? N\u2019est-il pas plus humaniste que celui qui endosse le r\u00f4le de vengeur d\u2019une humanit\u00e9 souffrante&nbsp;?<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><span class=\"has-inline-color has-black-color\">Des relations familiales chaotiques<\/span><\/strong><\/h2>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-justify\">Alors qu\u2019il n\u2019est \u00e2g\u00e9 que de 17 ans, un nouvel \u00e9v\u00e9nement tragique se produit. Le jeune Arthur perd son p\u00e8re qui se suicide. Une nouvelle fois saisit par la mis\u00e8re de la vie, il a l\u2019intime conviction que sa m\u00e8re est responsable du suicide de son p\u00e8re. Cette situation ne fera qu\u2019aggraver leur relation d\u00e9j\u00e0 chaotique. Il est plus que vraisemblable que tous deux se d\u00e9testent. Schopenhauer d\u00e9teste le c\u00f4t\u00e9 mondain de sa m\u00e8re et la consid\u00e8re comme vaniteuse et superficielle. Au cours d\u2019une altercation, prenant entre ses mains la th\u00e8se du doctorat de son fils, <em>De la Quadruple Racine du principe de raison suffisante<\/em>, qu\u2019elle qualifia \u00ab&nbsp;d\u2019une chose pour les laborantins&nbsp;\u00bb, la r\u00e9ponse cinglante du jeune Arthur ne se fit pas attendre&nbsp;:&nbsp;<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-justify\"><em>\u00ab&nbsp;On lira encore mes \u0153uvres lorsqu\u2019on pourra \u00e0 peine trouver l\u2019une des tiennes dans un d\u00e9barras.&nbsp;\u00bb<\/em><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-justify\">Une affirmation qui semble ind\u00e9cente \u00e0 l\u2019\u00e9poque, sa m\u00e8re \u00e9tant une romanci\u00e8re \u00e0 succ\u00e8s et une amie du c\u00e9l\u00e8bre Johann Wolfgang von Goethe, mais pourtant belle et bien v\u00e9ridique aujourd\u2019hui.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Ces tensions avec sa m\u00e8re ne s\u2019ach\u00e8veront jamais. Quelques ann\u00e9es plus tard, il la fustige dans son ouvrage <em>Pr\u00e9sences<\/em>, lui vouant une haine presque visc\u00e9rale&nbsp;:<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-justify\"><em>\u00ab&nbsp;Madame ma m\u00e8re recevait tandis que mon p\u00e8re mourait dans la solitude, et s\u2019amusait tandis qu\u2019il souffrait les plus amers tourments, tel est l\u2019amour des femmes.&nbsp;\u00bb<\/em><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-justify\">Apr\u00e8s une \u00e9ni\u00e8me dispute, Arthur, qui ne correspondait d\u00e9j\u00e0 plus que par lettres interpos\u00e9es avec sa m\u00e8re, d\u00e9cide de quitter le domicile familial et ne reverra jamais sa m\u00e8re. Johanna meurt en 1838 en le d\u00e9sh\u00e9ritant, ce qui ne fera qu\u2019aggraver l\u2019image qu\u2019il gardera de sa m\u00e8re.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><span class=\"has-inline-color has-black-color\">Une empathie d\u00e9mesur\u00e9e pour les animaux<\/span><\/strong><\/h2>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-justify\">Tr\u00e8s probablement marqu\u00e9 par ces relations hostiles et d\u00e9chirantes avec sa m\u00e8re, Schopenhauer se tiendra tout au long de sa vie \u00e0 l\u2019\u00e9cart des femmes, \u00e0 l\u2019exception de quelques relations tarif\u00e9es. Il consid\u00e8re qu\u2019elles assujettissent l\u2019homme de par leur attrait sexuel et que l\u2019homme a tout int\u00e9r\u00eat \u00e0 se lib\u00e9rer de leur influence. Il m\u00e8nera une vie de c\u00e9libataire et n\u2019aura pour seul compagnon que son ins\u00e9parable caniche. Son chien, qu\u2019il appelle <em>Atma<\/em>, qui signifie <em>\u00e2me du monde<\/em>, est d\u2019ailleurs un de ses h\u00e9ritiers. Une anecdote est d\u2019ailleurs relat\u00e9e par le musicologue Schnyder von Wartensee et t\u00e9moigne de sa consid\u00e9ration si extraordinaire \u00e0 l\u2019\u00e9gard de son chien&nbsp;:<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-justify\"><em>\u00ab Un jour, un voyageur venu \u00e0 notre table raconta une histoire arriv\u00e9e r\u00e9cemment et tout \u00e0 fait charmante \u00e0 propos d&#8217;un tour r\u00e9ussi par un chien. Schopenhauer \u00e9couta le r\u00e9cit avec la plus grande attention et dit : \u00ab Oui, ce que vous nous racontez l\u00e0 est certainement vrai. J&#8217;y reconnais mes propres chiens. Ils sont sup\u00e9rieurs aux hommes. J\u2019ai [&#8230;] un caniche, et quand il fait une b\u00eatise, je lui dis : \ufb01, tu n\u2019es pas un chien, tu n\u2019es qu&#8217;un homme. Oui, un homme&nbsp;! Tu devrais avoir honte. Alors il est tout honteux et va se coucher dans un coin. \u00bb Tout le monde se tut, tandis que Schopenhauer souriait f\u00e9rocement. [&#8230;] Je lui dis alors \u00e0 haute voix : \u00ab Herr Doktor, un homme qui appelle son chien \u2018homme\u2019 quand il veut l\u2019injurier, un tel homme, ne devrait-on pas l\u2019appeler \u2018chien\u2019 quand on veut lui faire honneur ? \u00bb [&#8230;] Schopenhauer dit alors : \u00ab Mais oui, je n&#8217;aurais rien contre. \u00bb<\/em><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-justify\">Schopenhauer est extr\u00eamement sensible aux animaux et leur voue une v\u00e9ritable compassion. Il fulmine d\u2019ailleurs le c\u00e9l\u00e8bre philosophe Baruch Spinoza qui prend un malin plaisir \u00e0 torturer les mouches.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><span class=\"has-inline-color has-black-color\">Son rapport \u00e0 l&#8217;art<\/span><\/strong><\/h2>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-justify\">Il a \u00e9galement une grande consid\u00e9ration de l\u2019art. Selon lui, l\u2019art peut apporter la v\u00e9rit\u00e9 au monde. La musique particuli\u00e8rement, qui apaise le vouloir vivre et la connaissance m\u00e9taphysique du monde&nbsp;: l\u2019art est contemplation, v\u00e9n\u00e9ration. La contemplation repr\u00e9sente pour lui la rupture avec la chaine de causalit\u00e9. Le propre du g\u00e9nie est sa capacit\u00e9 \u00e0 isoler une chose au sein de la nature et de rompre avec le rapport pragmatique du r\u00e9el. Isoler une chose, c\u2019est en saisir l\u2019essence profonde et v\u00e9ritable. La musique repr\u00e9sente \u00e0 ses yeux l\u2019affirmation tragique de l\u2019existence et affirme que la connaissance du monde m\u00e9taphysique est musicale. Pour lui, la musique est l\u2019expression fondamentale du monde. Schopenhauer adore Mozart et Beethoven et s\u2019adonne m\u00eame \u00e0 la pratique de la fl\u00fbte. N\u2019est-ce pas l\u00e0 une nouvelle contradiction que de consid\u00e9rer Schopenhauer comme un pessimiste absolu, alors m\u00eame qu\u2019il est musicien&nbsp;? La musique n\u2019est-elle pas une affirmation tragique de l\u2019existence&nbsp;? Nietzsche, qui rencontre d\u2019ailleurs Schopenhauer \u00e0 travers Richard Wagner, \u00e9crit \u00e0 ce propos dans <em>Par-del\u00e0 le bien et le mal<\/em>&nbsp;:<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-justify\"><em>\u00ab&nbsp;Mais celui qui a profond\u00e9ment senti combien cette proposition est fausse, insipide et sentimentale, dans un univers dont l\u2019essence m\u00eame est la volont\u00e9 de puissance, devra se souvenir que Schopenhauer, bien qu\u2019il f\u00fbt pessimiste, s\u2019est amus\u00e9 \u00e0 jouer de la fl\u00fbte\u2026 tous les jours, apr\u00e8s le repas&nbsp;: qu\u2019on lise l\u00e0-dessus son biographe. Et je me demande, en passant, si un pessimiste, un n\u00e9gateur de Dieu et de l\u2019univers qui s\u2019arr\u00eate devant la morale, [\u2026] a le droit de se dire v\u00e9ritablement pessimiste&nbsp;?&nbsp;\u00bb<\/em><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><span class=\"has-inline-color has-black-color\">L&#8217;influence de la philosophie indienne<\/span><\/strong><\/h2>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-justify\">La philosophie de Schopenhauer ne peut quoiqu\u2019il en soit se r\u00e9duire au pessimisme et se rapproche davantage de la pens\u00e9e indienne, notamment du Veda, auquel il se r\u00e9f\u00e8re \u00e9norm\u00e9ment, et du bouddhisme. C\u2019est une philosophie essentiellement construite sur le refus et le rejet de toute souffrance&nbsp;; cons\u00e9quence sans doute d\u2019une trop grande attention port\u00e9e \u00e0 la douleur, ce qui se manifeste par un d\u00e9sint\u00e9r\u00eat pour le monde, par un retrait volontaire suivi d\u2019un assoupissement des sens.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">\u00c0 titre de comparaison, on peut notamment retrouver ce rapport tr\u00e8s prononc\u00e9 \u00e0 la sensibilit\u00e9, \u00e0 la piti\u00e9, \u00e0 cette tendresse \u00e0 fleur de peau chez Jean-Jacques Rousseau. Schopenhauer adore lire les moralistes fran\u00e7ais et admire Montaigne, La Rochefoucauld, La Bruy\u00e8re ou Chamfort. Il adore en particulier Voltaire, \u00e0 qui il emprunte la limpidit\u00e9 de son style. Notons tout de m\u00eame que Schopenhauer est antir\u00e9volution et plut\u00f4t lib\u00e9ral sur le plan politique et maintient une position ambigu\u00eb entre la pens\u00e9e des Lumi\u00e8res et la pens\u00e9e romantique.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><span class=\"has-inline-color has-black-color\">Sa haine envers Hegel<\/span><\/strong><\/h2>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-justify\">Enfin, on peut assur\u00e9ment affirmer que Schopenhauer d\u00e9teste Hegel, qu\u2019il qualifie de <em>\u00ab&nbsp;philosophe universitaire<\/em>&nbsp;\u00bb. Il hait sa philosophie qu\u2019il qualifie de \u00ab<em> colossale mystification<\/em>&nbsp;\u00bb qui constitue \u00ab&nbsp;<em>le verbiage le plus creux [\u2026], le galimatias le plus stupide qui ait jamais \u00e9t\u00e9 entendu, du moins en dehors de maisons de fous<\/em>&nbsp;\u00bb. Outre sa philosophie, Schopenhauer voue, \u00e0 n\u2019en pas douter, une haine visc\u00e9rale de ce que repr\u00e9sente Hegel&nbsp;: lui, le grand ma\u00eetre de l\u2019universit\u00e9 de Berlin, le g\u00e9nie de la philosophie universitaire et allemande, le reconnu, le populaire.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><span class=\"has-inline-color has-black-color\">Sa vision de l&#8217;universit\u00e9<\/span><\/strong><\/h2>\n\n\n\n<p><\/p>\n\n\n\n<p>Il se montre \u00e9galement d\u2019une v\u00e9h\u00e9mence totale \u00e0 l\u2019encontre de l\u2019universit\u00e9, qui ne repr\u00e9sente \u00e0 ses yeux qu\u2019un prolongement de l\u2019id\u00e9ologie de l\u2019\u00c9tat (et comment lui donner tort). Il \u00e9crit \u00e0 ce propos&nbsp;:<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-justify\"><em>\u00ab&nbsp;L&#8217;innocente jeunesse se rend \u00e0 l&#8217;Universit\u00e9 pleine d&#8217;une confiance na\u00efve, et consid\u00e8re avec respect les pr\u00e9tendus possesseurs de tout savoir, et surtout le scrutateur pr\u00e9somptif de notre existence, l&#8217;homme dont elle entend proclamer avec enthousiasme la gloire par mille bouches et aux le\u00e7ons duquel elle voit assister des hommes d\u2019\u00c9tat charg\u00e9s d&#8217;ann\u00e9es. Elle se rend donc l\u00e0, pr\u00eate \u00e0 apprendre, \u00e0 croire et \u00e0 adorer. Si maintenant on lui pr\u00e9sente, sous le nom de philosophie, un amas d&#8217;id\u00e9es \u00e0 rebours, une doctrine de l&#8217;identit\u00e9 de l&#8217;\u00eatre et du non-\u00eatre, un assemblage de mots qui emp\u00eache tout cerveau sain de penser, un galimatias qui rappelle un asile d&#8217;ali\u00e9n\u00e9s, le tout chamarr\u00e9 par surcro\u00eet de traits d&#8217;une \u00e9paisse ignorance et d&#8217;une colossale inintelligence, alors l&#8217;innocente jeunesse d\u00e9pourvue de jugement sera pleine de respect aussi pour un pareil fatras, s&#8217;imaginera que la philosophie consiste en un abracadabra de ce genre, et elle s&#8217;en ira avec un cerveau paralys\u00e9 o\u00f9 les mots d\u00e9sormais passeront pour des id\u00e9es&nbsp;; elle se trouvera donc \u00e0 jamais dans l&#8217;impossibilit\u00e9 d&#8217;\u00e9mettre des id\u00e9es v\u00e9ritables, et son esprit sera ch\u00e2tr\u00e9.&nbsp;\u00bb<\/em><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><span class=\"has-inline-color has-black-color\">Le monde comme volont\u00e9 et comme repr\u00e9sentation<\/span><\/strong><\/h2>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-justify\">Schopenhauer d\u00e9finit le monde en deux parties appartenant \u00e0 un m\u00eame \u00e9l\u00e9ment&nbsp;: le monde de la volont\u00e9 et le monde de la repr\u00e9sentation. Le monde comme repr\u00e9sentation correspond \u00e0 la vision du monde que nous percevons, mais il n\u2019est pas le vrai monde. La repr\u00e9sentation est ce que Schopenhauer d\u00e9finit comme la face externe du monde, comme n\u2019\u00e9tant qu\u2019une facette du monde&nbsp;: elle est ce que nous percevons, ce que nous analysons et \u00e0 laquelle nous essayons de donner un sens via la science, l\u2019intelligence ou la raison. Le monde de la repr\u00e9sentation est \u00e9galement contenu par l\u2019espace et le temps. Il est limit\u00e9 par ces deux facteurs, puisqu\u2019on ne peut pas se repr\u00e9senter une chose hors du temps et de l\u2019espace. On ne peut pas se repr\u00e9senter l\u2019infinit\u00e9, comme on ne peut pas se repr\u00e9senter l\u2019intemporalit\u00e9.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Schopenhauer se situe au-del\u00e0 de tout mat\u00e9rialisme et de tout id\u00e9alisme. Pour lui, le pass\u00e9 et l\u2019avenir appartiennent au monde de la repr\u00e9sentation. La seule \u00e9ternit\u00e9 qui existe, c\u2019est l\u2019instant. On retrouve une id\u00e9e similaire dans l\u2019\u0153uvre <em>Ainsi parlait Zarathoustra<\/em> de Nietzsche&nbsp;: puisqu\u2019il n\u2019y a pas de commencement au pass\u00e9 et pas d\u2019aboutissement au futur, ce sont donc deux infinies qui se rejoignent et par cons\u00e9quent ne font qu\u2019un (deux infinies ne pouvant coexister sans se limiter l\u2019une l\u2019autre). Ainsi, le pass\u00e9 et le futur sont n\u00e9cessairement reli\u00e9s et continus et ne forment en r\u00e9alit\u00e9 qu\u2019une seule et m\u00eame ligne. <a href=\"https:\/\/www.youtube.com\/channel\/UCipyNJTrWAdyT0YMb3PkiMA\" target=\"_blank\" rel=\"noreferrer noopener\">Julien Rochedy<\/a>, dans son ouvrage consacr\u00e9 \u00e0 la philosophie nietzsch\u00e9enne <em><a href=\"https:\/\/www.rochedy.com\/livres\/nietzsche-lactuel\/\" target=\"_blank\" rel=\"noreferrer noopener\">Nietzsche l\u2019actuel<\/a><\/em>, explicite cette th\u00e8se&nbsp;:<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-justify\"><em>\u00ab&nbsp;L\u2019existence revient toujours sur elle-m\u00eame dans un mouvement perp\u00e9tuel que nous \u00e9prouvons vaguement \u00e0 travers le temps, mais qui n\u2019est au final qu\u2019une simple perspective. En somme, l\u2019\u00e9ternit\u00e9, le divin, le tout, l\u2019infini \u2013 le pass\u00e9 et le futur r\u00e9unis \u2013 c\u2019est l\u2019instant.&nbsp;\u00bb<\/em><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-justify\">Le monde de la volont\u00e9 est quant \u00e0 lui la face interne du monde, le fond insaisissable de la r\u00e9alit\u00e9 qui ne peut ni \u00eatre con\u00e7u par l\u2019esprit, ni saisi par l\u2019intellect. La volont\u00e9 \u00e9chappe \u00e0 l\u2019espace et au temps. M\u00e9taphoriquement, le monde comme repr\u00e9sentation ne serait que la partie visible de l\u2019iceberg, lorsque le monde comme volont\u00e9 serait la partie immerg\u00e9e. Nous ne connaissons donc que la repr\u00e9sentation du monde, pas la volont\u00e9. Selon Schopenhauer, le monde de la repr\u00e9sentation n\u2019est que l\u2019expression du monde de la volont\u00e9 qui est l\u2019essence du monde. Le monde de la repr\u00e9sentation est per\u00e7u comme une imposture, un monde d\u2019illusions qui nous fait nous consid\u00e9rer comme sup\u00e9rieurs \u00e0 ce que nous sommes r\u00e9ellement. L\u2019homme est un animal conceptuel capable de se repr\u00e9senter intellectuellement le monde et de s\u2019en former des images conceptuelles gr\u00e2ce \u00e0 sa conscience et son intellect. Pour Schopenhauer, l\u2019homme est donc un animal conceptuel, c\u2019est-\u00e0-dire qui a la conscience intellectuelle du monde de la repr\u00e9sentation. Nous sommes ainsi capables de comprendre comment le monde fonctionne, mais incapables de comprendre pourquoi il fonctionne, puisque nous ne sommes pas capables de comprendre le monde comme volont\u00e9.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Nous pouvons cependant avoir une conscience indirecte du monde de la volont\u00e9 gr\u00e2ce au monde de la repr\u00e9sentation. Le monde de la repr\u00e9sentation constitue le moyen par lequel s\u2019exprime le monde de la volont\u00e9, par lequel il se manifeste et devient accessible. Nous sommes des expressions de la volont\u00e9. Ainsi, si nous \u00e9tions capables de nous conna\u00eetre nous-m\u00eame, nous serions capables de conna\u00eetre une facette de la volont\u00e9, a minima de conna\u00eetre l\u2019aspect de la volont\u00e9 qui se manifeste \u00e0 travers nous. Nous sommes capables de comprendre comment fonctionne l\u2019homme, mais nous sommes pourtant incapables de comprendre pourquoi il fonctionne. Nous savons que nous vivons, mais nous ne savons pas pourquoi nous vivons. La volont\u00e9 pour Schopenhauer n\u2019a pas de raison d\u2019\u00eatre, ce qui signifie que la vie n\u2019a pas de raison d\u2019\u00eatre non plus. Notre existence est donc absurde&nbsp;: elle n\u2019a ni sens, ni origine, ni finalit\u00e9&nbsp;; elle est. La volont\u00e9 est. Elle s\u2019exprime \u00e0 travers nous sans que nous puissions en comprendre le sens et n\u2019a pour seul but que de se perp\u00e9tuer. Nous ne sommes en fait que le transport qu\u2019a choisi la volont\u00e9 pour s\u2019exprimer. La volont\u00e9 \u00e9chappant \u00e0 l\u2019espace et au temps, elle est donc intemporelle, informe, \u00e9ternelle et infinie et se perp\u00e9tue ind\u00e9finiment \u00e0 travers les \u00eatres vivants.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Pourquoi vivons-nous&nbsp;? Pourquoi avons-nous envie de vivre&nbsp;? Et pourquoi tenons-nous tant \u00e0 la vie&nbsp;?<\/p>\n\n\n\n<p class=\"has-text-align-justify\">&nbsp;\u00c0 l\u2019instar de chaque \u00eatre vivant, nous poss\u00e9dons entre autre un instinct de survie auquel nous ob\u00e9issons. Il n\u2019est pas rationnel, pourtant, nous continuons de lui ob\u00e9ir sans \u00eatre capables de comprendre pourquoi nous lui ob\u00e9issons, si ce n\u2019est pour rester en vie. Nous ne sommes pas capables de comprendre pourquoi nous voulons survivre, pourtant nous voulons survivre. Tout comme un animal bless\u00e9 se d\u00e9bat pour sauver sa peau. Pour Schopenhauer, cette volont\u00e9 n\u2019a aucune raison d\u2019\u00eatre, n\u2019a aucune logique, n\u2019a aucun sens autre que de se perp\u00e9tuer&nbsp;; et en cela, elle est tragique. Il consid\u00e8re que l\u2019homme est esclave de la volont\u00e9&nbsp;: l\u2019homme pense \u00eatre ma\u00eetre de sa vie, or ce n\u2019est qu\u2019une illusion. L\u2019homme croit \u00eatre libre mais n\u2019est en r\u00e9alit\u00e9 que le moyen d\u2019expression de la volont\u00e9. L\u2019homme travaille toute sa vie pour que puisse se perp\u00e9tuer la volont\u00e9. Il \u0153uvre \u00e0 perp\u00e9tuer une vie qu\u2019il ne comprend pas, qui n\u2019a aucun sens ni aucune logique. Nous sommes donc condamn\u00e9s \u00e0 vivre -nous n\u2019avons pas choisi d\u2019\u00eatre en vie- et \u00e0 ex\u00e9cuter la volont\u00e9 du monde.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">En cela, la vie pour Schopenhauer ne peut \u00eatre que source de souffrance. Si l\u2019existence n\u2019a pas pour but imm\u00e9diat la douleur, alors notre existence n\u2019a aucun but en soi. Schopenhauer consid\u00e8re qu\u2019il est absurde d\u2019admettre que notre douleur sans fin, qui nait de la mis\u00e8re inh\u00e9rente \u00e0 la vie, ne soit qu\u2019un pur accident et non le but m\u00eame de l\u2019existence. Car si chaque malheur nous semble \u00eatre une exception, le malheur en g\u00e9n\u00e9ral en est la r\u00e8gle. Nous ne remarquons sur le champ que tout ce qui est douloureux. Nous ne remarquons pas notre bonne sant\u00e9 en g\u00e9n\u00e9ral, mais seulement le point l\u00e9ger qui nous blesse. Nous ne nous posons aucune question lorsque nous sommes heureux, mais nous nous rendons instantan\u00e9ment compte lorsque nous sommes malheureux. Lorsque nous faisons glisser notre main le long d\u2019une surface lisse, nous ne ressentons quelque chose que lorsque qu\u2019il y a un accro, une rayure, une bosse, une asp\u00e9rit\u00e9. L\u2019homme n\u2019est donc pas fait pour le bonheur, puisqu\u2019il ne ressent que la douleur. Seule la douleur est positive, car nous la ressentons&nbsp;; tandis que le bonheur est n\u00e9gatif, car nous ne le ressentons pas. Le bonheur ne d\u00e9signe donc \u00e0 ses yeux rien de positif, mais seulement la cessation momentan\u00e9e d\u2019une douleur. Le contraire de la douleur n\u2019est donc pas le plaisir, mais l\u2019ennui&nbsp;: puisque le plaisir est une illusion, il est n\u00e9gatif, et que nous ne ressentons que la douleur. Le th\u00e8me de l\u2019ennui est d\u2019ailleurs tr\u00e8s fr\u00e9quent chez les moralistes.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><span class=\"has-inline-color has-black-color\">L\u2019amour selon Schopenhauer<\/span><\/strong><\/h2>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-justify\">Si notre existence est tragique, elle peut sembler difficilement supportable pour le commun des mortels. Mais aussi chaotique, aussi profond\u00e9ment insens\u00e9e soit-elle, notre existence doit \u00eatre en mesure de nous satisfaire pour que puisse se perp\u00e9tuer la volont\u00e9. Ainsi vient l\u2019amour. Pour Schopenhauer, l\u2019amour n\u2019est qu\u2019une illusion, \u00e0 l\u2019image de notre libert\u00e9. L\u2019amour ne repr\u00e9sente rien d\u2019autre \u00e0 ses yeux que l\u2019instrument de la volont\u00e9 qui se manifeste pour que nous consentions \u00e0 la perp\u00e9tuer. L\u2019amour n\u2019est qu\u2019un leurre qui n\u2019a pour seul but que de nous tromper en nous faisant accepter de perp\u00e9tuer la volont\u00e9. D\u2019apr\u00e8s lui, l\u2019amour et le d\u00e9sir sexuel sont consubstantiels, identiques&nbsp;: l\u2019amour ne repr\u00e9sente que la forme culturellement et moralement acceptable du d\u00e9sir sexuel. L\u2019amour est d\u00e9peint comme une hypocrisie qui nous permet d\u2019accepter que notre seul but est de nous reproduire pour perp\u00e9tuer la volont\u00e9. Un homme qui pr\u00e9tend \u00e9chapper \u00e0 cette r\u00e8gle, qui pr\u00e9tend aimer sinc\u00e8rement, de fa\u00e7on inconditionnelle et d\u00e9sint\u00e9ress\u00e9e est per\u00e7u chez Schopenhauer comme un vaniteux qui n\u2019accepte pas d\u2019\u00eatre r\u00e9duit au rang d\u2019esclave de la volont\u00e9. Nous avons en nous cet \u00e9go, cette vanit\u00e9 qui nous fait accepter, parfois m\u00eame adorer cette imposture qu\u2019est l\u2019amour. Nous voulons aimer. Nous aimons aimer. Nous avons le sentiment que l\u2019amour est la n\u00e9cessit\u00e9 absolue de notre existence.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Pour Schopenhauer, tout cela n\u2019est que baliverne. L\u2019amour est une illusion qui annihile toute r\u00e9volte en nous. L\u2019amour nous conditionne \u00e0 tol\u00e9rer -voire \u00e0 aimer- la dictature de la volont\u00e9. La sexualit\u00e9 ne repr\u00e9sente que le fond primitif de la vie. L\u2019expression la plus authentique et la plus pure de la volont\u00e9 se manifeste \u00e0 travers la sexualit\u00e9&nbsp;: elle est le moyen d\u2019expression le plus brut de la volont\u00e9. Tout comme nous ne comprenons pas pourquoi nous vivons, nous ne comprenons pas non plus pourquoi nous d\u00e9sirons une personne. Nous sommes capables de comprendre les m\u00e9canismes du d\u00e9sir sexuel mais nous sommes incapables de comprendre pourquoi nous d\u00e9sirons. Nous prenons v\u00e9ritablement conscience de l\u2019absurdit\u00e9 de la sexualit\u00e9 lorsque l\u2019acte est accompli. Lorsque celui-ci s\u2019ach\u00e8ve, nous sommes envahis par un sentiment de honte, parfois de d\u00e9gout. Ce sentiment n\u2019est autre qu\u2019un \u00e9clair de lucidit\u00e9 sur la bestialit\u00e9 qui sommeille en nous et de la force irrationnelle et d\u00e9chain\u00e9e de la volont\u00e9. Schopenhauer r\u00e9sume parfaitement sa pens\u00e9e en une phrase&nbsp;:<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><em>\u00ab&nbsp;Le sexe et la procr\u00e9ation ne sont qu\u2019une dictature de l\u2019esp\u00e8ce.&nbsp;\u00bb<\/em><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><span class=\"has-inline-color has-black-color\">Le renoncement et la r\u00e9volte du faible<\/span><\/strong><\/h2>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-justify\">Pour Schopenhauer, la vie est une trag\u00e9die absolue. Nous souffrons perp\u00e9tuellement et sommes incapables de saisir la volont\u00e9, la r\u00e9alit\u00e9. Nous sommes constamment soumis \u00e0 la volont\u00e9. Nous sommes \u00e0 l\u2019image de ces bagnards de Toulon, mis\u00e9rables esclaves d\u2019une r\u00e9alit\u00e9 que nous ne saisissons pas et qui nous a d\u00e9j\u00e0 condamn\u00e9 \u00e0 la souffrance perp\u00e9tuelle. Ainsi s\u2019op\u00e8re la r\u00e9volte de l\u2019esclave ou du faible. Plut\u00f4t que d\u2019\u00eatre dans l\u2019acceptation de la r\u00e9alit\u00e9 du monde, Schopenhauer adopte une position fataliste&nbsp;: puisque je suis un esclave, puisque je n\u2019ai aucun contr\u00f4le sur la volont\u00e9 du monde, alors je ne veux \u00eatre rien et me r\u00e9signe. Pour lui, il faut faire cesser cette trag\u00e9die en cassant la spirale de la volont\u00e9&nbsp;: il faut cesser de procr\u00e9er. Faire preuve de lucidit\u00e9 et de compassion \u00e0 l\u2019\u00e9gard de nos descendants. Comprendre que le monde n\u2019a pas de sens, est absurde, qu\u2019il n\u2019est que souffrance et par cons\u00e9quent, avoir un peu de compassion pour autrui et pour nous-m\u00eame en cessant cette souffrance du cycle de la vie.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Le suicide n\u2019apparait cependant pas chez Schopenhauer comme une solution, il d\u00e9signe selon lui davantage une affirmation passionn\u00e9e du vouloir-vivre que sa n\u00e9gation r\u00e9elle. Pour authentiquement s\u2019affranchir, il faut atteindre le <em>Nirvana<\/em>. Si le vouloir-vivre d\u00e9signe une puissance sans repos qui nous condamne \u00e0 la douleur \u00e9ternelle, il nous faut alors nous d\u00e9tacher de cette puissance de la vie universelle. Ce n\u2019est donc pas la mort que nous devons chercher, puisque celle-ci d\u00e9signe l\u2019affranchissement d\u2019une individualit\u00e9, mais l\u2019an\u00e9antissement supr\u00eame du vouloir, l\u2019extinction du d\u00e9sir humain, entrainant donc la fin du cycle des r\u00e9incarnations, c\u2019est-\u00e0-dire le <em>Nirvana<\/em>. Schopenhauer s\u2019attaque sans cesse au d\u00e9sir renaissant et au vouloir-vivre \u00e9ternel dont il faut selon lui se d\u00e9tacher pour atteindre l\u2019ultime s\u00e9r\u00e9nit\u00e9. On retrouve ici l\u2019\u00e9norme influence du bouddhisme dans la pens\u00e9e de Schopenhauer, ce que Nietzsche qualifie d\u2019une religion intelligente, sensible \u00e0 l\u2019exc\u00e8s et tol\u00e9rante mais qui n\u2019en reste pas moins une religion de faible qui pousse \u00e0 la lassitude de la civilisation.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Ce refus permanent de la douleur, cette lassitude intellectuelle, cette pr\u00e9dominance de la piti\u00e9, cette r\u00e9duction de tous les probl\u00e8mes \u00e0 des questions de plaisir ou de douleur, ce rejet de toute forme de divin ou de grandeur qu\u2019illustre Schopenhauer&nbsp;: Nietzsche le d\u00e9signe comme une d\u00e9cadence et un nihilisme europ\u00e9en. Nietzsche h\u00e9rite de la pens\u00e9e de Schopenhauer et la met au pinacle&nbsp;: il en tire l\u2019essence principale et la sublime. La morale du faible devient la morale du fort. Ce passage est illustr\u00e9 \u00e0 merveille une nouvelle fois dans le livre de Julien Rochedy&nbsp;:<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><em>\u00ab&nbsp;Je [Nietzsche] suis un d\u00e9cadent, \u00e9crit-il en toute conscience, mais je me suis r\u00e9volt\u00e9 ci-contre.&nbsp;\u00bb<\/em><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-justify\"><em>\u00ab&nbsp;Sa gloire [\u00e0 propos de Nietzsche], c\u2019est d\u2019\u00eatre capable de transformer toute la faiblesse de son \u00eatre pour la sublimer en une force ultra lucide.&nbsp;\u00bb<\/em><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><span class=\"has-inline-color has-black-color\">La r\u00e9volte en nous<\/span><\/strong><\/h2>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-justify\">Nietzsche appelle \u00e0 la r\u00e9volte en nous, quand Schopenhauer ne faisait que la contempler et l\u2019admirer. Il appelle \u00e0 se surpasser, \u00e0 transformer cette force nihiliste en nous en une force cr\u00e9atrice et h\u00e9ro\u00efque de l\u2019amour de la vie&nbsp;:<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><em>\u00ab&nbsp;Vainqueurs sont ceux qui savent se transformer.&nbsp;\u00bb<\/em><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-text-align-justify\">\u00c9crit-il. Mais comment nous transformer&nbsp;? Comment nous r\u00e9volter face \u00e0 ce nihilisme&nbsp;? C\u2019est l\u00e0 tout l\u2019enjeu de notre si\u00e8cle et de ceux \u00e0 venir. C\u2019est l\u00e0 un combat permanent qu\u2019il faudra mener avec patience, bravoure et sagesse afin de retrouver notre grandeur pass\u00e9e. Pour que se perp\u00e9tue et prosp\u00e8re une civilisation rayonnante et grandiose.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><em>Faisons vivre le bon, le juste, le beau.<\/em><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"has-inline-color has-black-color\">Sources\u00a0:<\/span><\/h2>\n\n\n\n<p><a href=\"https:\/\/www.lemonde.fr\/a-la-une\/article\/2003\/07\/25\/schopenhauer-l-incompris_328871_3208.html\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.lemonde.fr\/a-la-une\/article\/2003\/07\/25\/schopenhauer-l-incompris_328871_3208.html<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/www.schopenhauer.fr\/biographie\/schopenhuaer-et-son-chien.html\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.schopenhauer.fr\/biographie\/schopenhuaer-et-son-chien.html<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/la-philosophie.com\/schopenhauer-femmes\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/la-philosophie.com\/schopenhauer-femmes<\/a><\/p>\n\n\n\n<p><a href=\"http:\/\/eve-adam.over-blog.com\/2015\/02\/schopenhauer-et-les-femmes.html#:~:text=Ce%20%C3%A0%20quoi%20le%20philosophe,r%C3%A9cit%20de%20ses%20conqu%C3%AAtes%20amoureuses\" target=\"_blank\" rel=\"noreferrer noopener\">http:\/\/eve-adam.over-blog.com\/2015\/02\/schopenhauer-et-les-femmes.html#:~:text=Ce%20%C3%A0%20quoi%20le%20philosophe,r%C3%A9cit%20de%20ses%20conqu%C3%AAtes%20amoureuses<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/www.schopenhauer.fr\/biographie\/bagne.html#:~:text=Visite%20de%20Schopenhauer%20au%20bagne%20de%20Toulon&amp;text=Lors%20d'une%20visite%20au,compagnons%20d'une%20colonie%20p%C3%A9nitentiaire%20\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.schopenhauer.fr\/biographie\/bagne.html#:~:text=Visite%20de%20Schopenhauer%20au%20bagne%20de%20Toulon&amp;text=Lors%20d&#8217;une%20visite%20au,compagnons%20d&#8217;une%20colonie%20p%C3%A9nitentiaire%20<\/a><\/p>\n\n\n\n<figure class=\"wp-block-embed-wordpress wp-block-embed is-type-wp-embed is-provider-la-philosophie-com-cours-resumes-amp-citations-de-philosophie\"><div class=\"wp-block-embed__wrapper\">\n<span class=\"aqPFsS1t6\"><blockquote class=\"wp-embedded-content\" data-secret=\"XJFQjBm8bJ\"><a href=\"https:\/\/la-philosophie.com\/citations-schopenhauer\">Citations d&#8217;Arthur Schopenhauer<\/a><\/blockquote><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"\u00ab\u00a0Citations d&#8217;Arthur Schopenhauer\u00a0\u00bb &#8212; La-Philosophie.com : Cours, R\u00e9sum\u00e9s &amp; Citations de Philosophie\" src=\"https:\/\/la-philosophie.com\/citations-schopenhauer\/embed#?secret=XJFQjBm8bJ\" data-secret=\"XJFQjBm8bJ\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/span>\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<span class=\"L9zUwu3XC4KGA2Ja6DfYbtEl8QVBPTnH10mqiSpjFNyodcRsxIWhZ5keOvr7\"><div class=\"responsive-video\"><iframe title=\"Schopenhauer (2\/5) : Le pessimisme\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/PDK5n4r6k4I?start=924&#038;feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/span>\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<span class=\"n7EBucdpawIiJ18Ke9jRFOxhzSmQgM6WbqVyCUDHZAs3Xl\"><div class=\"responsive-video\"><iframe title=\"Schopenhauer (1\/5) : L&#039;homme\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/X-XZ_Ac7E4c?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/span>\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<span class=\"YnSW8MmROc5LUyN1P20ieKpdwqr\"><div class=\"responsive-video\"><iframe title=\"SCHOPENHAUER - La m\u00e9taphysique, l&#039;amour, le sexe \ud83d\udccf\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/iVkkzzxBnQ0?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/span>\n<\/div><\/figure>\n\n\n\n<p><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Arthur_Schopenhauer\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/fr.wikipedia.org\/wiki\/Arthur_Schopenhauer<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/la-philosophie.com\/schopenhauer-philosophie\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/la-philosophie.com\/schopenhauer-philosophie<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/www.rochedy.com\/livres\/nietzsche-lactuel\/\" target=\"_blank\" rel=\"noreferrer noopener\">Nietzsche l\u2019actuel, introduction \u00e0 la philosophie nietzsch\u00e9enne, Julien Rochedy<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Introduction Arthur Schopenhauer est un philosophe allemand atypique connu pour son immense influence sur de nombreux philosophes, \u00e9crivains et artistes [&hellip;]<\/p>","protected":false},"author":1,"featured_media":1342,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[4,3],"tags":[13,16,30],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Qui est vraiment Arthur Schopenhauer ? - The Conservative Enthusiast<\/title>\n<meta name=\"description\" content=\"Qui est vraiment le myst\u00e9rieux Arthur Schopenhauer ? D\u00e9couvrez notre article complet sur The Conservative Enthusiast !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/conservativenthusiast.com\/en\/qui-est-vraiment-arthur-schopenhauer\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qui est vraiment Arthur Schopenhauer ? - The Conservative Enthusiast\" \/>\n<meta property=\"og:description\" content=\"Qui est vraiment le myst\u00e9rieux Arthur Schopenhauer ? D\u00e9couvrez notre article complet sur The Conservative Enthusiast !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/conservativenthusiast.com\/en\/qui-est-vraiment-arthur-schopenhauer\/\" \/>\n<meta property=\"og:site_name\" content=\"The Conservative Enthusiast\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-26T13:03:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-11T14:43:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/conservativenthusiast.com\/wp-content\/uploads\/2020\/09\/Arthur_Schopenhauer_colorized-829x1024.png\" \/>\n\t<meta property=\"og:image:width\" content=\"829\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Alexis.L\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alexis.L\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"25 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/conservativenthusiast.com\/qui-est-vraiment-arthur-schopenhauer\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/conservativenthusiast.com\/qui-est-vraiment-arthur-schopenhauer\/\"},\"author\":{\"name\":\"Alexis.L\",\"@id\":\"https:\/\/conservativenthusiast.com\/#\/schema\/person\/3edd83a60aed483f95ebc876aeac7feb\"},\"headline\":\"Qui est vraiment Arthur Schopenhauer ?\",\"datePublished\":\"2020-09-26T13:03:02+00:00\",\"dateModified\":\"2020-11-11T14:43:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/conservativenthusiast.com\/qui-est-vraiment-arthur-schopenhauer\/\"},\"wordCount\":4965,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\/\/conservativenthusiast.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/conservativenthusiast.com\/qui-est-vraiment-arthur-schopenhauer\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/conservativenthusiast.com\/wp-content\/uploads\/2020\/09\/Arthur_Schopenhauer_colorized.png\",\"keywords\":[\"Biographie\",\"Philosophie\",\"Schopenhauer\"],\"articleSection\":[\"Biographie\",\"Philosophie\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/conservativenthusiast.com\/qui-est-vraiment-arthur-schopenhauer\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/conservativenthusiast.com\/qui-est-vraiment-arthur-schopenhauer\/\",\"url\":\"https:\/\/conservativenthusiast.com\/qui-est-vraiment-arthur-schopenhauer\/\",\"name\":\"Qui est vraiment Arthur Schopenhauer ? - The Conservative Enthusiast\",\"isPartOf\":{\"@id\":\"https:\/\/conservativenthusiast.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/conservativenthusiast.com\/qui-est-vraiment-arthur-schopenhauer\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/conservativenthusiast.com\/qui-est-vraiment-arthur-schopenhauer\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/conservativenthusiast.com\/wp-content\/uploads\/2020\/09\/Arthur_Schopenhauer_colorized.png\",\"datePublished\":\"2020-09-26T13:03:02+00:00\",\"dateModified\":\"2020-11-11T14:43:56+00:00\",\"description\":\"Qui est vraiment le myst\u00e9rieux Arthur Schopenhauer ? D\u00e9couvrez notre article complet sur The Conservative Enthusiast !\",\"breadcrumb\":{\"@id\":\"https:\/\/conservativenthusiast.com\/qui-est-vraiment-arthur-schopenhauer\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/conservativenthusiast.com\/qui-est-vraiment-arthur-schopenhauer\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/conservativenthusiast.com\/qui-est-vraiment-arthur-schopenhauer\/#primaryimage\",\"url\":\"https:\/\/conservativenthusiast.com\/wp-content\/uploads\/2020\/09\/Arthur_Schopenhauer_colorized.png\",\"contentUrl\":\"https:\/\/conservativenthusiast.com\/wp-content\/uploads\/2020\/09\/Arthur_Schopenhauer_colorized.png\",\"width\":2314,\"height\":2860,\"caption\":\"Arthur Schopenhauer\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/conservativenthusiast.com\/qui-est-vraiment-arthur-schopenhauer\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/conservativenthusiast.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Qui est vraiment Arthur Schopenhauer ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/conservativenthusiast.com\/#website\",\"url\":\"https:\/\/conservativenthusiast.com\/\",\"name\":\"The Conservative Enthusiast\",\"description\":\"La plateforme de r\u00e9information, de partage et d&#039;apprentissage des conservateurs.\",\"publisher\":{\"@id\":\"https:\/\/conservativenthusiast.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/conservativenthusiast.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/conservativenthusiast.com\/#organization\",\"name\":\"The Conservative Enthusiast\",\"url\":\"https:\/\/conservativenthusiast.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/conservativenthusiast.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/i0.wp.com\/conservativeenthusiast.com\/wp-content\/uploads\/2020\/06\/LOGO-CE-MINI.png?fit=3867%2C1180&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/conservativeenthusiast.com\/wp-content\/uploads\/2020\/06\/LOGO-CE-MINI.png?fit=3867%2C1180&ssl=1\",\"width\":3867,\"height\":1180,\"caption\":\"The Conservative Enthusiast\"},\"image\":{\"@id\":\"https:\/\/conservativenthusiast.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/conservativenthusiast.com\/#\/schema\/person\/3edd83a60aed483f95ebc876aeac7feb\",\"name\":\"Alexis.L\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/conservativenthusiast.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e276145ad3a64170e9c68564bb9e4280?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e276145ad3a64170e9c68564bb9e4280?s=96&d=mm&r=g\",\"caption\":\"Alexis.L\"},\"description\":\"Si vous appr\u00e9ciez les articles de ce r\u00e9dacteur et que vous souhaitez en d\u00e9couvrir davantage sur lui ou ses \u00e9crits, vous pouvez consulter tous ses articles en cliquant sur son pseudo ou en apprendre plus sur notre page \\\"Notre \u00e9quipe\\\". Vous pouvez \u00e9galement le suivre sur ses diff\u00e9rents r\u00e9seaux sociaux ci-dessous.\",\"url\":\"https:\/\/conservativenthusiast.com\/en\/author\/admin6171\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Qui est vraiment Arthur Schopenhauer ? - The Conservative Enthusiast","description":"Qui est vraiment le myst\u00e9rieux Arthur Schopenhauer ? D\u00e9couvrez notre article complet sur The Conservative Enthusiast !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/conservativenthusiast.com\/en\/qui-est-vraiment-arthur-schopenhauer\/","og_locale":"en_GB","og_type":"article","og_title":"Qui est vraiment Arthur Schopenhauer ? - The Conservative Enthusiast","og_description":"Qui est vraiment le myst\u00e9rieux Arthur Schopenhauer ? D\u00e9couvrez notre article complet sur The Conservative Enthusiast !","og_url":"https:\/\/conservativenthusiast.com\/en\/qui-est-vraiment-arthur-schopenhauer\/","og_site_name":"The Conservative Enthusiast","article_published_time":"2020-09-26T13:03:02+00:00","article_modified_time":"2020-11-11T14:43:56+00:00","og_image":[{"width":829,"height":1024,"url":"https:\/\/conservativenthusiast.com\/wp-content\/uploads\/2020\/09\/Arthur_Schopenhauer_colorized-829x1024.png","type":"image\/png"}],"author":"Alexis.L","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Alexis.L","Estimated reading time":"25 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/conservativenthusiast.com\/qui-est-vraiment-arthur-schopenhauer\/#article","isPartOf":{"@id":"https:\/\/conservativenthusiast.com\/qui-est-vraiment-arthur-schopenhauer\/"},"author":{"name":"Alexis.L","@id":"https:\/\/conservativenthusiast.com\/#\/schema\/person\/3edd83a60aed483f95ebc876aeac7feb"},"headline":"Qui est vraiment Arthur Schopenhauer ?","datePublished":"2020-09-26T13:03:02+00:00","dateModified":"2020-11-11T14:43:56+00:00","mainEntityOfPage":{"@id":"https:\/\/conservativenthusiast.com\/qui-est-vraiment-arthur-schopenhauer\/"},"wordCount":4965,"commentCount":1,"publisher":{"@id":"https:\/\/conservativenthusiast.com\/#organization"},"image":{"@id":"https:\/\/conservativenthusiast.com\/qui-est-vraiment-arthur-schopenhauer\/#primaryimage"},"thumbnailUrl":"https:\/\/conservativenthusiast.com\/wp-content\/uploads\/2020\/09\/Arthur_Schopenhauer_colorized.png","keywords":["Biographie","Philosophie","Schopenhauer"],"articleSection":["Biographie","Philosophie"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/conservativenthusiast.com\/qui-est-vraiment-arthur-schopenhauer\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/conservativenthusiast.com\/qui-est-vraiment-arthur-schopenhauer\/","url":"https:\/\/conservativenthusiast.com\/qui-est-vraiment-arthur-schopenhauer\/","name":"Qui est vraiment Arthur Schopenhauer ? - The Conservative Enthusiast","isPartOf":{"@id":"https:\/\/conservativenthusiast.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/conservativenthusiast.com\/qui-est-vraiment-arthur-schopenhauer\/#primaryimage"},"image":{"@id":"https:\/\/conservativenthusiast.com\/qui-est-vraiment-arthur-schopenhauer\/#primaryimage"},"thumbnailUrl":"https:\/\/conservativenthusiast.com\/wp-content\/uploads\/2020\/09\/Arthur_Schopenhauer_colorized.png","datePublished":"2020-09-26T13:03:02+00:00","dateModified":"2020-11-11T14:43:56+00:00","description":"Qui est vraiment le myst\u00e9rieux Arthur Schopenhauer ? D\u00e9couvrez notre article complet sur The Conservative Enthusiast !","breadcrumb":{"@id":"https:\/\/conservativenthusiast.com\/qui-est-vraiment-arthur-schopenhauer\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/conservativenthusiast.com\/qui-est-vraiment-arthur-schopenhauer\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/conservativenthusiast.com\/qui-est-vraiment-arthur-schopenhauer\/#primaryimage","url":"https:\/\/conservativenthusiast.com\/wp-content\/uploads\/2020\/09\/Arthur_Schopenhauer_colorized.png","contentUrl":"https:\/\/conservativenthusiast.com\/wp-content\/uploads\/2020\/09\/Arthur_Schopenhauer_colorized.png","width":2314,"height":2860,"caption":"Arthur Schopenhauer"},{"@type":"BreadcrumbList","@id":"https:\/\/conservativenthusiast.com\/qui-est-vraiment-arthur-schopenhauer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/conservativenthusiast.com\/"},{"@type":"ListItem","position":2,"name":"Qui est vraiment Arthur Schopenhauer ?"}]},{"@type":"WebSite","@id":"https:\/\/conservativenthusiast.com\/#website","url":"https:\/\/conservativenthusiast.com\/","name":"The Conservative Enthusiast","description":"La plateforme de r\u00e9information, de partage et d&#039;apprentissage des conservateurs.","publisher":{"@id":"https:\/\/conservativenthusiast.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/conservativenthusiast.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/conservativenthusiast.com\/#organization","name":"The Conservative Enthusiast","url":"https:\/\/conservativenthusiast.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/conservativenthusiast.com\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/conservativeenthusiast.com\/wp-content\/uploads\/2020\/06\/LOGO-CE-MINI.png?fit=3867%2C1180&ssl=1","contentUrl":"https:\/\/i0.wp.com\/conservativeenthusiast.com\/wp-content\/uploads\/2020\/06\/LOGO-CE-MINI.png?fit=3867%2C1180&ssl=1","width":3867,"height":1180,"caption":"The Conservative Enthusiast"},"image":{"@id":"https:\/\/conservativenthusiast.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/conservativenthusiast.com\/#\/schema\/person\/3edd83a60aed483f95ebc876aeac7feb","name":"Alexis.L","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/conservativenthusiast.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e276145ad3a64170e9c68564bb9e4280?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e276145ad3a64170e9c68564bb9e4280?s=96&d=mm&r=g","caption":"Alexis.L"},"description":"Si vous appr\u00e9ciez les articles de ce r\u00e9dacteur et que vous souhaitez en d\u00e9couvrir davantage sur lui ou ses \u00e9crits, vous pouvez consulter tous ses articles en cliquant sur son pseudo ou en apprendre plus sur notre page \"Notre \u00e9quipe\". Vous pouvez \u00e9galement le suivre sur ses diff\u00e9rents r\u00e9seaux sociaux ci-dessous.","url":"https:\/\/conservativenthusiast.com\/en\/author\/admin6171\/"}]}},"_links":{"self":[{"href":"https:\/\/conservativenthusiast.com\/en\/wp-json\/wp\/v2\/posts\/1333"}],"collection":[{"href":"https:\/\/conservativenthusiast.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conservativenthusiast.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conservativenthusiast.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/conservativenthusiast.com\/en\/wp-json\/wp\/v2\/comments?post=1333"}],"version-history":[{"count":10,"href":"https:\/\/conservativenthusiast.com\/en\/wp-json\/wp\/v2\/posts\/1333\/revisions"}],"predecessor-version":[{"id":2788,"href":"https:\/\/conservativenthusiast.com\/en\/wp-json\/wp\/v2\/posts\/1333\/revisions\/2788"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conservativenthusiast.com\/en\/wp-json\/wp\/v2\/media\/1342"}],"wp:attachment":[{"href":"https:\/\/conservativenthusiast.com\/en\/wp-json\/wp\/v2\/media?parent=1333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conservativenthusiast.com\/en\/wp-json\/wp\/v2\/categories?post=1333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conservativenthusiast.com\/en\/wp-json\/wp\/v2\/tags?post=1333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}